{"id":4094,"date":"2017-08-04T15:45:09","date_gmt":"2017-08-04T15:45:09","guid":{"rendered":"https:\/\/marketingweb.com.mx\/blog\/?p=4094"},"modified":"2017-08-04T15:50:25","modified_gmt":"2017-08-04T15:50:25","slug":"diseno-web-tabasco","status":"publish","type":"post","link":"https:\/\/marketingweb.com.mx\/blog\/diseno-web-tabasco\/","title":{"rendered":"Dise\u00f1o web Tabasco"},"content":{"rendered":"<h1>Dise\u00f1o web Tabasco<\/h1>\n<p><a href=\"https:\/\/marketingweb.com.mx\/blog\/wp-content\/uploads\/potter-and-web_slide_1_desktop.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-2696\" src=\"https:\/\/marketingweb.com.mx\/blog\/wp-content\/uploads\/potter-and-web_slide_1_desktop-300x118.jpg\" alt=\"Dise\u00f1o web Tabasco\" width=\"300\" height=\"118\" srcset=\"https:\/\/marketingweb.com.mx\/blog\/wp-content\/uploads\/potter-and-web_slide_1_desktop-300x118.jpg 300w, https:\/\/marketingweb.com.mx\/blog\/wp-content\/uploads\/potter-and-web_slide_1_desktop-768x302.jpg 768w, https:\/\/marketingweb.com.mx\/blog\/wp-content\/uploads\/potter-and-web_slide_1_desktop-1024x403.jpg 1024w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<h2>Dise\u00f1o web Tabasco<\/h2>\n<div class=\"page\" title=\"P\u00e1gina 105\">\n<div class=\"layoutArea\">\n<div class=\"column\">\n<p><a href=\"https:\/\/marketingweb.com.mx\/diseno-web.html\">Rastreo, evaluaci\u00f3n y mantenimiento del sitio<\/a><\/p>\n<p>El rastreo, la evaluaci\u00f3n y el mantenimiento de las tareas que se realizan en forma posterior a su puesta en l\u00ednea. Fern\u00e1ndez-Coca (1998) afirma que el dise\u00f1o web Toluca web es un ente vivo y requiere continuamente que se modifique los contenidos, se sustituyan los documentos, se corrijan los datos o se mejore la interfaz gr\u00e1fica y Dise\u00f1o web Toluca.<\/p>\n<p>En el Dise\u00f1o web Toluca del Departamento de Comunicaci\u00f3n, ninguna de estas tareas se realizaron. El rastreo permite obtener informaci\u00f3n sobre los usuarios que visitan el sitio, la evaluaci\u00f3n permite corregir errores, y el mantenimiento conserva actualizado la informaci\u00f3n presentada. Es de importancia vital para el Dise\u00f1o web Toluca &#8211; especialmente las comerciales, porque lo permiten conocer la preferencia de los usuarios, el tiempo de permanencia en el sitio, las p\u00e1ginas m\u00e1s y menos visitadas; En s\u00edntesis, informaci\u00f3n que permite ofrecer un mejor producto y adaptarlo a las exigencias de los visitantes. El rastreo est\u00e1 en estrecha relaci\u00f3n con el servidor y su configuraci\u00f3n, ya que est\u00e1 all\u00ed donde se debe incorporar el software para recopilar y clasificar los datos. De existir esta informaci\u00f3n en el servidor de la UNRC,<\/p>\n<p>La evaluaci\u00f3n de un sitio es una herramienta indispensable para su administraci\u00f3n. Al no realizarse esta tarea, no hay corregir posibles defectos o adaptar el producto a las exigencias de los usuarios.<\/p>\n<p>Pero el aspecto m\u00e1s importante est\u00e1 relacionado con el mantenimiento o la actualizaci\u00f3n del sitio. La informaci\u00f3n que actualmente se muestra en muchos casos inexacta o se refiere a eventos ya transcurridos.<\/p>\n<p>&nbsp;<\/p>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"page\" title=\"P\u00e1gina 106\">\n<div class=\"layoutArea\"><\/div>\n<div class=\"layoutArea\">\n<div class=\"column\">\n<p>Algunos de los problemas relacionados con la falta de mantenimiento del dise\u00f1o web Toluca hijo:<\/p>\n<ul>\n<li>\u00a0 El listado de documentos est\u00e1 desactualizado. Se mencionan profesores que ya no pertenecen al Departamento y no se han incluido en los m\u00e1s recientes. En algunos casos, tambi\u00e9n la direcci\u00f3n de correo electr\u00f3nico es inexacta.<\/li>\n<li>\u00a0 La revista &#8220;Temas y Problemas&#8221; est\u00e1 disponible en sus n\u00fameros 6 y 7, mientras que la edici\u00f3n impresa va por el n\u00famero 10.<\/li>\n<li>ise\u00f1o web Toluca \u00a0Las producciones de los estudiantes que se encuentran en el \u00c1rea de Producci\u00f3n corresponden a los estudiantes que cursan las materias correspondientes durante el a\u00f1o en el cual se D, y posteriormente no se actualiz\u00f3. Adem\u00e1s, desde la fecha de inicio de las subsecciones Televisiva, Videogr\u00e1fica y Radio tienen un cartel que indica que se hallan en construcci\u00f3n.<\/li>\n<li>\u00a0 El Endicom se realiz\u00f3 del 11 al 15 de octubre de 1999, sin embargo la informaci\u00f3n que anuncia su inminente realizaci\u00f3n y invitando a presentar trabajos todav\u00eda se encuentra en l\u00ednea.<\/li>\n<li>\u00a0 La informaci\u00f3n sobre el encuentro Qui\u00e9n es qui\u00e9n corresponde a su edici\u00f3n 1999 y no se ha actualizado.En s\u00edntesis, la actualizaci\u00f3n del desarrollo web aparece como una necesidad. No nos referimos \u00fanicamente a modificar los elementos inexactos, sino tambi\u00e9n a considerar la actualizaci\u00f3n del sitio como parte de su proceso de desarrollo e implementaci\u00f3n.<\/li>\n<\/ul>\n<\/div>\n<\/div>\n<\/div>\n<h3><strong><em>Dise\u00f1o web Tabasco<\/em><\/strong><\/h3>\n<p>#Disenoweb<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Dise\u00f1o web Tabasco Dise\u00f1o web Tabasco Rastreo, evaluaci\u00f3n y mantenimiento del sitio El rastreo, la evaluaci\u00f3n y el mantenimiento de las tareas que se realizan en forma posterior a su puesta en l\u00ednea. Fern\u00e1ndez-Coca (1998) afirma que el dise\u00f1o web Toluca web es un ente vivo y requiere continuamente que se modifique los contenidos, se [&hellip;]<\/p>\n","protected":false},"author":18,"featured_media":2705,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_joinchat":[],"footnotes":""},"categories":[55],"tags":[68,364,363,46,47,691],"class_list":["post-4094","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-diseno-web","tag-desarrollo-web","tag-desarrollo-web-df","tag-desarrollo-web-guadalajara","tag-diseno-web","tag-diseno-web-guadalajara","tag-diseno-web-tabasco"],"_links":{"self":[{"href":"https:\/\/marketingweb.com.mx\/blog\/wp-json\/wp\/v2\/posts\/4094","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/marketingweb.com.mx\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/marketingweb.com.mx\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/marketingweb.com.mx\/blog\/wp-json\/wp\/v2\/users\/18"}],"replies":[{"embeddable":true,"href":"https:\/\/marketingweb.com.mx\/blog\/wp-json\/wp\/v2\/comments?post=4094"}],"version-history":[{"count":0,"href":"https:\/\/marketingweb.com.mx\/blog\/wp-json\/wp\/v2\/posts\/4094\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/marketingweb.com.mx\/blog\/wp-json\/wp\/v2\/media\/2705"}],"wp:attachment":[{"href":"https:\/\/marketingweb.com.mx\/blog\/wp-json\/wp\/v2\/media?parent=4094"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/marketingweb.com.mx\/blog\/wp-json\/wp\/v2\/categories?post=4094"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/marketingweb.com.mx\/blog\/wp-json\/wp\/v2\/tags?post=4094"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}