{"id":3739,"date":"2017-05-31T14:54:03","date_gmt":"2017-05-31T14:54:03","guid":{"rendered":"https:\/\/marketingweb.com.mx\/blog\/?p=3739"},"modified":"2017-05-31T14:59:42","modified_gmt":"2017-05-31T14:59:42","slug":"desarrollo-web-monterrey","status":"publish","type":"post","link":"https:\/\/marketingweb.com.mx\/blog\/desarrollo-web-monterrey\/","title":{"rendered":"Desarrollo web Monterrey"},"content":{"rendered":"<h1>Desarrollo web Monterrey<\/h1>\n<figure id=\"attachment_2661\" aria-describedby=\"caption-attachment-2661\" style=\"width: 300px\" class=\"wp-caption alignnone\"><a href=\"https:\/\/marketingweb.com.mx\/blog\/wp-content\/uploads\/10-Web-Design-Trends-for-2015.png\"><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-2661\" src=\"https:\/\/marketingweb.com.mx\/blog\/wp-content\/uploads\/10-Web-Design-Trends-for-2015-300x190.png\" alt=\"Desarrollo web Monterrey \" width=\"300\" height=\"190\" srcset=\"https:\/\/marketingweb.com.mx\/blog\/wp-content\/uploads\/10-Web-Design-Trends-for-2015-300x190.png 300w, https:\/\/marketingweb.com.mx\/blog\/wp-content\/uploads\/10-Web-Design-Trends-for-2015-768x485.png 768w, https:\/\/marketingweb.com.mx\/blog\/wp-content\/uploads\/10-Web-Design-Trends-for-2015-1024x647.png 1024w, https:\/\/marketingweb.com.mx\/blog\/wp-content\/uploads\/10-Web-Design-Trends-for-2015.png 1280w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><figcaption id=\"caption-attachment-2661\" class=\"wp-caption-text\"><em>Desarrollo web Monterrey<\/em><\/figcaption><\/figure>\n<p><strong>Desarrollo web Monterrey\u00a0<\/strong><\/p>\n<p><strong>4.-Dise\u00f1o del sitio<\/strong><\/p>\n<p>El dise\u00f1o del sitio Web del Departamento de Ciencias de la Comunicaci\u00f3n cuenta con una misma estructura que se repite a lo largo de sus p\u00e1ginas. La misma se muestra en la figura 2.2 (p\u00e1g. 96) y est\u00e1 conformada por:<\/p>\n<ul>\n<li><strong>Banda de localizaci\u00f3n.<\/strong> Se\u00f1ala la secci\u00f3n o el tema de la p\u00e1gina y la pertenencia al Departamento de Ciencias de la Comunicaci\u00f3n. Se repite en cada p\u00e1gina, en el mismo lugar y con id\u00e9ntica tipograf\u00eda y colores (naranja, negro y blanco). Se trata de un archivo gr\u00e1fico en formato GIF, de 650 p\u00edxeles de largo por 33 p\u00edxeles de alto. No posee enlaces.<\/li>\n<li><strong>Hipertexto de navegaci\u00f3n b\u00e1sica.<\/strong> Por debajo de la banda superior, las p\u00e1ginas presentan v\u00ednculos hipertextuales que se\u00f1alan el recorrido de navegaci\u00f3n. En negrita se resalta el lugar donde se encuentra el usuario y hacia la izquierda se despliega el recorrido realizado. No existe vinculaci\u00f3n hacia otras secciones y para hacia un \u00e1rea diferente el usuario debe retornar a la <em>home page<\/em>.<\/li>\n<li><strong>Cuerpo de p\u00e1gina.<\/strong> Est\u00e1 conformado por texto e im\u00e1genes y \u2013en algunos casos- por v\u00ednculos que apuntan hacia uno mismo lugar dentro de la p\u00e1gina. Los formatos para presentar los gr\u00e1ficos de las p\u00e1ginas son GIF o JPG. El hipertexto dentro del cuerpo de la p\u00e1gina se\u00f1ala hacia otras partes del mismo documento, hacia otras p\u00e1ginas del sitio o hacia sitios externos. No existe una indicaci\u00f3n que permita al usuario saber de qu\u00e9 tipo de v\u00ednculo se trata.<\/li>\n<\/ul>\n<h3>paginas web gratis<\/h3>\n<p>&nbsp;<\/p>\n<p>Estructura de p\u00e1gina del actual sitio Web del Departamento<\/p>\n<ul>\n<li><strong>Enlaces inferiores.<\/strong> Casi sobre el final, las p\u00e1ginas del sitio poseen uno o dos botones que enlazan hacia la <em>home page<\/em> o secciones como \u201cCarreras y Planes\u201d o \u201c\u00c1rea de Producci\u00f3n\u201d. No hay v\u00ednculo hacia otras secciones del sitio, sino solo aquella que contiene la p\u00e1gina que se est\u00e1 visitando.<\/li>\n<li><strong>Pie de p\u00e1gina.<\/strong> Al final de cada una de las p\u00e1ginas se encuentra la informaci\u00f3n de <em>copyright<\/em>, el a\u00f1o de creaci\u00f3n de la p\u00e1gina, la referencia hacia la instituci\u00f3n a la que pertenece el sitio \u2013Facultad de Ciencias Humanas, Universidad Nacional de R\u00edo Cuarto- y una direcci\u00f3n de correo electr\u00f3nico.<\/li>\n<\/ul>\n<p>En general, podemos afirmar que las diferentes p\u00e1ginas del sitio mantienen una estructura m\u00e1s o menos semejante, a excepci\u00f3n de la <em>home page<\/em> y algunas p\u00e1ginas interiores como la que brinda informaci\u00f3n sobre las materias (carrera3.htm). Algunas p\u00e1ginas presentan errores en la parte inferior al haberse omitido un salto de l\u00ednea entre el texto \u201cFacultad de Ciencias Humanas\u201d y \u201cDepartamento de Ciencias de la Comunicaci\u00f3n\u201d.<\/p>\n<p>Una vez analizadas las p\u00e1ginas en su estructura general, nos detendremos brevemente en algunos puntos espec\u00edficos del dise\u00f1o.<\/p>\n<ul>\n<li><strong>Longitud de p\u00e1gina.<\/strong> En general, se utilizan p\u00e1ginas cortas con algunas excepciones como la p\u00e1gina donde se muestra informaci\u00f3n sobre las materias de las carreras (carrera3.htm).<\/li>\n<li>Naranja, negro y blanco son los colores predominantes del sitio. Los v\u00ednculos hipertextuales presentan su fisonom\u00eda cl\u00e1sica: texto en azul y subrayado, mientras que los botones con hiperv\u00ednculos mantienen los tres colores predominantes de la interfaz. El color naranja escogido no pertenece a la paleta <em>web safe<\/em> que garantiza una reproducci\u00f3n sin alteraciones en usuarios con diferente equipamiento de <em>hardware <\/em>y <em>software<\/em>.<\/li>\n<li><strong>Gr\u00e1ficos.<\/strong> Como se\u00f1alamos anteriormente, se emplean solamente los formatos GIF y JPG, y se excluye PNG. Los GIFs utilizados son est\u00e1ticos y no existen animaciones en la p\u00e1gina. Para la inserci\u00f3n de los gr\u00e1ficos se utilizaron las etiquetas WIDTH y HEIGHT, a fines de que el usuario pueda visualizar el tama\u00f1o de los gr\u00e1ficos antes de su descarga. Tambi\u00e9n se incluy\u00f3 la etiqueta ALT para a\u00f1adir informaci\u00f3n sobre el gr\u00e1fico.<\/li>\n<li>No se utilizaron iconos en las p\u00e1ginas del sitio. En su lugar, hay gr\u00e1ficos que simulan botones de una aplicaci\u00f3n multimedia donde un peque\u00f1o dibujo acompa\u00f1a la informaci\u00f3n que indica hacia d\u00f3nde enlaza el v\u00ednculo. En la <em>home page<\/em> los gr\u00e1ficos tambi\u00e9n est\u00e1n acompa\u00f1ados de bandas con informaci\u00f3n textual.<\/li>\n<li>Se utiliz\u00f3 la tipograf\u00eda \u201cArial\u201d en tama\u00f1o 2 para el cuerpo de la p\u00e1gina donde se encuentra la informaci\u00f3n. Sobre la redacci\u00f3n, se trata de textos breves y utilizan algunos recursos visuales para facilitar el \u201chojear\u201d la p\u00e1gina como listas con vi\u00f1etas, separaci\u00f3n de p\u00e1rrafos y l\u00edneas no demasiado extensas. En referencia a la titulaci\u00f3n de los textos, la misma est\u00e1 realizada con im\u00e1genes gr\u00e1ficas lo que provoca problemas como: a) se ve primero el cuerpo del texto que el t\u00edtulo; b) los t\u00edtulos no pueden ser hallados por los motores de b\u00fasqueda; c) en cuanto al estilo, se observa que no hay consistencia entre el t\u00edtulo y el bloque de texto, ya que se emplean tipograf\u00edas y colores diferentes.<\/li>\n<li>Se utilizan tablas con porcentajes relativos para evitar l\u00edneas de texto demasiado extensas que recorran la ventana de navegaci\u00f3n de una punta hacia otra. No se utilizan recursos como tablas anidadas o tablas apiladas.<\/li>\n<li>No se utilizan.<\/li>\n<li><strong>Contenido multimedia.<\/strong> Es escaso. En \u201c\u00c1rea de Producci\u00f3n\u201d se reproducen fotograf\u00edas, portadas de revistas y se puede descargar un archivo ejecutable que reproduce un sonomontaje.<\/li>\n<li><strong>Presentaci\u00f3n de enlaces.<\/strong> Como se se\u00f1al\u00f3 en el punto 2.2, las p\u00e1ginas no poseen v\u00ednculos estructurales para acceder a las diferentes secciones o \u00e1reas, solo se permite avanzar o retroceder en una misma l\u00ednea tem\u00e1ticojer\u00e1rquica. Los enlaces hipertextuales que aportan m\u00e1s informaci\u00f3n sobre un tema al que se est\u00e1 haciendo referencia son escasos.<\/li>\n<li><strong>Firma y fecha.<\/strong> Est\u00e1 presente en el pie de p\u00e1gina a lo largo de todo el sitio.<\/li>\n<li><strong>Derechos de autor y <em>copyright<\/em>.<\/strong> En el pie de p\u00e1gina se indica que el contenido pertenece a la UNRC, aunque no existe mayor informaci\u00f3n sobre c\u00f3mo proceder en caso que un usuario desee reproducir el contenido o realizar un v\u00ednculo hacia algunas de las p\u00e1ginas.,<\/li>\n<\/ul>\n<h3>crear pagina web<\/h3>\n<p><strong>4.1 Recapitulaci\u00f3n y s\u00edntesis sobre el dise\u00f1o del sitio<\/strong><\/p>\n<p>Por la cantidad de elementos que intervienen en el an\u00e1lisis del dise\u00f1o del sitio Web creemos importante sintetizar las consideraciones expresadas anteriormente y establecer algunos puntos generales que permitan identificar claramente situaciones problem\u00e1ticas. Por su importancia espec\u00edfica en un sitio y su dise\u00f1o diferentes, presentamos por separado el an\u00e1lisis de la <em>home page<\/em> y las p\u00e1ginas internas.<\/p>\n<p><em>Home page<\/em><\/p>\n<p>En nuestra opini\u00f3n, la p\u00e1gina principal del sitio es la que presenta el mayor n\u00famero de inconvenientes con respecto a su dise\u00f1o. En primer lugar, es preciso se\u00f1alar que la p\u00e1gina est\u00e1 compuesta casi en su totalidad por elementos gr\u00e1ficos, lo cual provoca que su descarga sea lenta. Si tomamos una velocidad de conexi\u00f3n promedio de 28.8 kbps, solamente el gr\u00e1fico de la derecha demora m\u00e1s de 20 segundos en descargarse en la computadora del usuario. Lynch y Horton (2000) se\u00f1alan que los dise\u00f1os m\u00e1s efectivos para la Web son aquellos donde se combina cuidadosamente texto, enlaces y elementos gr\u00e1ficos relativamente peque\u00f1os, premisa que est\u00e1 ausente en el dise\u00f1o en la <em>home page<\/em> del sitio.<\/p>\n<p>Por otra parte, si el usuario ha deshabilitado la opci\u00f3n de descarga de gr\u00e1ficos o no puede visualizarlos por alg\u00fan otro motivo (problemas en el servidor, velocidad de conexi\u00f3n muy baja) el 80% de la pantalla queda en blanco. Solamente hay informaci\u00f3n en formato de texto el l\u00edmite inferior donde se repiten los enlaces gr\u00e1ficos en hipertexto y se encuentra el pie de p\u00e1gina.<\/p>\n<p>Adem\u00e1s, la presencia de los v\u00ednculos alienados en la izquierda sugiere al usuario que los mismos se encontrar\u00e1n a lo largo de todas las p\u00e1ginas del sitio, cuando en realidad debe retornar a la <em>home page<\/em> para acceder a diferentes secciones.<\/p>\n<p>En cuanto a los aspectos positivos, se puede destacar que la <em>home page <\/em>presenta los rasgos distintivos de la interfase que se mantienen en las p\u00e1ginas interiores (colores, bordes redondeados en las barra que sirven de fondo al texto, tipograf\u00eda). A ello debe sumarse que la p\u00e1gina principal mantiene una consistencia gr\u00e1fica al utilizar un mismo estilo en los botones, mantener presente en la imagen de la derecha los colores predominantes como naranja, negro y blanco. Por otra parte, se utilizan gr\u00e1ficos sencillos que ilustran de las secciones hacia donde enlazan.<\/p>\n<p><em>P\u00e1ginas interiores<\/em><\/p>\n<p>Las p\u00e1ginas interiores mantienen una estructura sencilla que se repite a lo largo de cada una de ellas: banda de localizaci\u00f3n e identificaci\u00f3n del sitio, ruta de enlaces seguidos, cuerpo y pie de p\u00e1gina. La programaci\u00f3n de las p\u00e1ginas tambi\u00e9n es sencilla, puesto que se utilizan las etiquetas b\u00e1sicas del HTML.<\/p>\n<p>En general, no hay grandes fallas respecto del dise\u00f1o: la informaci\u00f3n de las p\u00e1ginas es legible, se identifica correctamente a trav\u00e9s de una banda localizadora y la ruta de enlaces permite recordar el recorrido y volver a cualquiera de los puntos anteriores. Sin embargo, existen varios aspectos sobre los cuales se pueden realizar mejoras.<\/p>\n<p>Uno de los principales puntos a considerar es que falta una mayor integraci\u00f3n gr\u00e1fica entre los elementos que componen el sitio para lograr un estilo m\u00e1s fuerte y consistente, que no se apoye solamente en los colores y la curvatura de las barras y figuras. Se hace necesario lograr una mayor unificaci\u00f3n entre el texto y los gr\u00e1ficos, con el fin de que el usuario pueda leer la p\u00e1gina en conjunto como una unidad visual. Se revela la importancia de contar con elementos como v\u00ednculos estructurales repetidos en cada una de las p\u00e1ginas, m\u00e1s espacio para los colores identificativos del sitio Web, o disposici\u00f3n de la informaci\u00f3n en bloques, para reforzar rasgos distintivos del sitio. En s\u00edntesis, es preciso pensar en un repertorio de elementos gr\u00e1ficos que le imprima mayor car\u00e1cter y personalidad al sitio Web, y que permita mostrar una interfaz m\u00e1s consistente.<\/p>\n<h3>sitio web<\/h3>\n<p>Otros aspectos relacionados con el dise\u00f1o susceptibles de ser mejorados son:<\/p>\n<ul>\n<li><strong>Control de longitud de p\u00e1gina en documentos extensos.<\/strong> Unificar el largo de las p\u00e1ginas y dividir aquellas que sean demasiado extensas (Fern\u00e1ndez-Coca, 1998; Lynch y Horton, 2000).<\/li>\n<li><strong>Desarrollar una barra de navegaci\u00f3n o una columna de enlaces.<\/strong> Para permitir una mejor navegaci\u00f3n del sitio e incorporar elementos de identificaci\u00f3n, podr\u00eda evaluarse la conveniencia de desarrollar una barra de navegaci\u00f3n o ubicar los enlaces estructurales en una columna (Lynch y Horton, 2000; Nielsen, 2000). El desarrollo de una iconograf\u00eda propia en el sitio Web tambi\u00e9n contribuye en ambos aspectos (Fern\u00e1ndez-Coca, 1998).<\/li>\n<li><strong>Utilizar colores <em>web safe<\/em>.<\/strong> Al menos en los grandes bloques de color del sitio, es aconsejable utilizar colores que se reproduzcan de igual modo en usuarios con diferente equipamiento de <em>hardware<\/em> o <em>software<\/em> (Lynch y Horton, 2000).<\/li>\n<li><strong>Optimizar la estructura del sitio para una resoluci\u00f3n.<\/strong> La banda identificativa del sitio posee un largo de 650 p\u00edxeles, con lo cual excede la pantalla en una resoluci\u00f3n de 640&#215;480 p\u00edxeles o es peque\u00f1a para una de 800&#215;600. Es conveniente organizar la estructura del sitio para que se adecue a una de estas resoluciones. Resulta interesante tambi\u00e9n considerar la posibilidad de desarrollar una estructura compatible con ambas resoluciones (Nielsen, 2000). En todo caso, el pie de p\u00e1gina deber\u00eda indicar si existe una resoluci\u00f3n recomendada.<\/li>\n<li><strong>Corregir la titulaci\u00f3n de textos y utilizaci\u00f3n de hipertexto.<\/strong> Como se se\u00f1al\u00f3 anteriormente, utilizar gr\u00e1ficos en la titulaci\u00f3n produce varios inconvenientes, por lo es aconsejable reemplazarlos por texto y estructurarlos de acuerdo con lo enunciado en el punto 3.4.7 del primer cap\u00edtulo. Adem\u00e1s, debe analizarse la posibilidad de utilizar hipertextos para ampliar informaci\u00f3n o establecer relaciones asociativas en el cuerpo central informativo de la p\u00e1gina.<\/li>\n<li><strong>Mejorar la presentaci\u00f3n de los v\u00ednculos.<\/strong> Como se\u00f1ala Nielsen (2000) a\u00f1adir t\u00edtulos a los v\u00ednculos presenta importantes ventajas y pr\u00e1cticamente ning\u00fan problema. Por otra parte, ya hemos insistido en la necesidad de desarrollar v\u00ednculos estructurales a las diferentes \u00e1reas o secciones del sitio. Estos v\u00ednculos deber\u00edan estar agrupados y convenientemente diferenciados del resto de los v\u00ednculos de las p\u00e1ginas.<\/li>\n<li><strong>A\u00f1adir informaci\u00f3n de <em>copyright <\/em>y derechos de autor.<\/strong> Debido a la facilidad con la cual es posible duplicar informaci\u00f3n en la Web, es necesario ofrecer a los usuarios una pol\u00edtica de derechos de autor, en la que se detalle si est\u00e1 permitida la reproducci\u00f3n de informaci\u00f3n, bajo qu\u00e9 condiciones y cu\u00e1les son las sanciones legales susceptibles de ser aplicadas en caso de violaci\u00f3n de las normativas (Fern\u00e1ndez-Coca, 1998).<\/li>\n<li><strong>Corregir defectos en pie de p\u00e1ginas.<\/strong> Algunas p\u00e1ginas presentan defectos en la informaci\u00f3n colocada al pie como falta de saltos de l\u00ednea o alineaci\u00f3n irregular.<\/li>\n<\/ul>\n<p><strong>Desarrollo web Monterrey<\/strong><\/p>\n<p><strong>#Disenoweb #paginasweb #desarrolloweb\u00a0<\/strong><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Desarrollo web Monterrey Desarrollo web Monterrey\u00a0 4.-Dise\u00f1o del sitio El dise\u00f1o del sitio Web del Departamento de Ciencias de la Comunicaci\u00f3n cuenta con una misma estructura que se repite a lo largo de sus p\u00e1ginas. La misma se muestra en la figura 2.2 (p\u00e1g. 96) y est\u00e1 conformada por: Banda de localizaci\u00f3n. Se\u00f1ala la secci\u00f3n [&hellip;]<\/p>\n","protected":false},"author":18,"featured_media":2667,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_joinchat":[],"footnotes":""},"categories":[55,540],"tags":[581,421,361,362,482,616],"class_list":["post-3739","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-diseno-web","category-marketing-digital","tag-agencia-de-desarrollo-de-paginas-web","tag-agencia-de-desarrollo-web","tag-agencia-de-desarrollo-web-df","tag-agencia-de-desarrollo-web-guadalajara","tag-agencia-de-desarrollo-web-mexico","tag-desarrollo-web-monterrey"],"_links":{"self":[{"href":"https:\/\/marketingweb.com.mx\/blog\/wp-json\/wp\/v2\/posts\/3739","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/marketingweb.com.mx\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/marketingweb.com.mx\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/marketingweb.com.mx\/blog\/wp-json\/wp\/v2\/users\/18"}],"replies":[{"embeddable":true,"href":"https:\/\/marketingweb.com.mx\/blog\/wp-json\/wp\/v2\/comments?post=3739"}],"version-history":[{"count":0,"href":"https:\/\/marketingweb.com.mx\/blog\/wp-json\/wp\/v2\/posts\/3739\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/marketingweb.com.mx\/blog\/wp-json\/wp\/v2\/media\/2667"}],"wp:attachment":[{"href":"https:\/\/marketingweb.com.mx\/blog\/wp-json\/wp\/v2\/media?parent=3739"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/marketingweb.com.mx\/blog\/wp-json\/wp\/v2\/categories?post=3739"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/marketingweb.com.mx\/blog\/wp-json\/wp\/v2\/tags?post=3739"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}