{"id":3513,"date":"2017-04-04T15:29:29","date_gmt":"2017-04-04T15:29:29","guid":{"rendered":"https:\/\/marketingweb.com.mx\/blog\/?p=3513"},"modified":"2017-04-04T15:33:01","modified_gmt":"2017-04-04T15:33:01","slug":"desarrollo-web-tlajomulco","status":"publish","type":"post","link":"https:\/\/marketingweb.com.mx\/blog\/desarrollo-web-tlajomulco\/","title":{"rendered":"Desarrollo web Tlajomulco"},"content":{"rendered":"<h1>Desarrollo web Tlajomulco<\/h1>\n<figure id=\"attachment_3492\" aria-describedby=\"caption-attachment-3492\" style=\"width: 300px\" class=\"wp-caption alignnone\"><a href=\"https:\/\/marketingweb.com.mx\/blog\/wp-content\/uploads\/7-1.png\"><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-3492\" src=\"https:\/\/marketingweb.com.mx\/blog\/wp-content\/uploads\/7-1-300x138.png\" alt=\"Desarrollo web Tlajomulco\" width=\"300\" height=\"138\" srcset=\"https:\/\/marketingweb.com.mx\/blog\/wp-content\/uploads\/7-1-300x138.png 300w, https:\/\/marketingweb.com.mx\/blog\/wp-content\/uploads\/7-1-768x353.png 768w, https:\/\/marketingweb.com.mx\/blog\/wp-content\/uploads\/7-1.png 798w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><figcaption id=\"caption-attachment-3492\" class=\"wp-caption-text\"><em>Desarrollo web Tlajomulco<\/em><\/figcaption><\/figure>\n<p><strong>Desarrollo web Tlajomulco.\u00a0<\/strong>Lynch y Horton (2000) se\u00f1alan que los formatos gr\u00e1ficos utilizados para la Web deben estar comprimidos por necesidad, debido al reducido ancho de banda con el que cuenta gran parte de los usuarios. Fern\u00e1ndez-Coca (1998) agrega que los gr\u00e1ficos utilizados en la World Wide Web tienen formato de mapa de bits<\/p>\n<p>Los formatos gr\u00e1ficos que se utilizan en los documentos Web son tres: GIF (<em>Graphic Interchange Format<\/em>), JPEG (<em>Joint Photographic Expert Group<\/em>) y PNG (<em>Portable Network Graphics<\/em>). Cada uno de ellos tiene sus caracter\u00edsticas en cuanto a cantidad de colores que admite, posibilidades de realizar animaci\u00f3n, canales de transparencia y factor de comprensi\u00f3n, ayudando esto al <strong>desarrollo web Tlajomulco<\/strong>.<\/p>\n<h3>Agencia de dise\u00f1o web Guadalajara<\/h3>\n<p><em>GIF<\/em><\/p>\n<p>Este tipo de archivos fue el utilizado por el Servicio de Informaci\u00f3n Compuserve en los a\u00f1os \u201980. Los dise\u00f1adores de documentos Web comenzaron a emplearlo porque encontraron en \u00e9l eficacia entre el tama\u00f1o del archivo y la calidad de los gr\u00e1ficos (Lynch y Horton, 2000).<\/p>\n<p>Su paleta de colores es de 8 bits (o 256 colores) y utiliza un sistema sencillo de compresi\u00f3n denominado <em>Lempel Zev Welch<\/em> o LZW para eliminar datos no necesarios sin perder informaci\u00f3n o distorsionar la imagen. Lynch y Horton (2000) se\u00f1alan que este tipo de compresi\u00f3n funciona bien en im\u00e1genes con zonas de color homog\u00e9neo, pero pierde eficacia con im\u00e1genes complejas con muchos colores y texturas diferentes. Es por ello que el formato GIF suele emplearse en logotipos, botones, ilustraciones sencillas con pocos colores o fondos de pantalla.<\/p>\n<p><strong>Desarrollo web Tlajomulco<\/strong><\/p>\n<p>Desde sus or\u00edgenes hasta la actualidad el formato GIF ha ido sumando una serie de caracter\u00edsticas y mejoras. Lynch y Horton (2000) se\u00f1alan algunas de ellas:<\/p>\n<ul>\n<li>Sin esta funci\u00f3n un archivo GIF se descarga desde arriba hacia abajo l\u00ednea por l\u00ednea. Por el contrario, un archivo GIF entrelazado muestra desde un primer momento toda la imagen en baja resoluci\u00f3n, y a medida que se va descargando el gr\u00e1fico desde la red la resoluci\u00f3n va mejorando. La ventaja de este sistema es que permite al usuario ver la totalidad de la imagen desde un comienzo y no necesita que se descargue toda la informaci\u00f3n del archivo para hacerse de una idea aproximada acerca del gr\u00e1fico con el que se encontrar\u00e1. Lynch y Horton (2000) recomiendan utilizar entrelazado s\u00f3lo en gr\u00e1ficos de gran tama\u00f1o, ya que en im\u00e1genes peque\u00f1as ralentiza el proceso de descarga. Los navegadores est\u00e1ndar como <em>Netscape Communicator<\/em> y <em>Microsoft Internet Explorer<\/em> soportan esta funci\u00f3n de los archivos GIF.<\/li>\n<li>Es una utilidad incorporada en una versi\u00f3n de GIF conocida se ver\u00e1 con los p\u00edxeles del color anterior.<\/li>\n<li><strong>Animaci\u00f3n.<\/strong> Es una caracter\u00edstica del formato GIF en su versi\u00f3n original a la cual no se le encontraba demasiada utilidad. Un solo archivo GIF permite incluir varias im\u00e1genes en forma secuencial con lo cual es posible que si se desplaza poco a poco una figura se logre el efecto de movimiento o animaci\u00f3n. Se utiliza principalmente para los carteles o <em>banners<\/em> publicitarios en la Web, aunque tambi\u00e9n suelen haber botones o im\u00e1genes animadas en los documentos. Lynch y Horton (2000) recomiendan evitar animar elementos in\u00fatilmente porque distraen la atenci\u00f3n del usuario. Las limitaciones t\u00e9cnicas de la animaci\u00f3n GIF son: a) no permiten control del usuario, quien solamente puede ver la animaci\u00f3n sin accionar sobre ella; y b) no hay compresi\u00f3n entre diferentes fotogramas, por lo cual una animaci\u00f3n de cinco cuadros de 10 <em>kilobytes<\/em> tendr\u00e1 un tama\u00f1o de 50 <em>kilobytes<\/em>.<\/li>\n<\/ul>\n<p><strong>Desarrollo web Tlajomulco.<\/strong><\/p>\n<p>#Desarrolloweb #dise\u00f1oweb #Agenciadedise\u00f1oweb<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Desarrollo web Tlajomulco Desarrollo web Tlajomulco.\u00a0Lynch y Horton (2000) se\u00f1alan que los formatos gr\u00e1ficos utilizados para la Web deben estar comprimidos por necesidad, debido al reducido ancho de banda con el que cuenta gran parte de los usuarios. Fern\u00e1ndez-Coca (1998) agrega que los gr\u00e1ficos utilizados en la World Wide Web tienen formato de mapa de [&hellip;]<\/p>\n","protected":false},"author":18,"featured_media":3492,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_joinchat":[],"footnotes":""},"categories":[55],"tags":[421,361,362,559,282,330,560,558],"class_list":["post-3513","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-diseno-web","tag-agencia-de-desarrollo-web","tag-agencia-de-desarrollo-web-df","tag-agencia-de-desarrollo-web-guadalajara","tag-agencia-de-desarrollo-web-zapopan","tag-agencia-de-diseno-web","tag-agencia-de-diseno-web-guadalajara","tag-agencia-de-diseno-web-zapopan","tag-desarrollo-web-tlajomulco"],"_links":{"self":[{"href":"https:\/\/marketingweb.com.mx\/blog\/wp-json\/wp\/v2\/posts\/3513","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/marketingweb.com.mx\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/marketingweb.com.mx\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/marketingweb.com.mx\/blog\/wp-json\/wp\/v2\/users\/18"}],"replies":[{"embeddable":true,"href":"https:\/\/marketingweb.com.mx\/blog\/wp-json\/wp\/v2\/comments?post=3513"}],"version-history":[{"count":0,"href":"https:\/\/marketingweb.com.mx\/blog\/wp-json\/wp\/v2\/posts\/3513\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/marketingweb.com.mx\/blog\/wp-json\/wp\/v2\/media\/3492"}],"wp:attachment":[{"href":"https:\/\/marketingweb.com.mx\/blog\/wp-json\/wp\/v2\/media?parent=3513"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/marketingweb.com.mx\/blog\/wp-json\/wp\/v2\/categories?post=3513"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/marketingweb.com.mx\/blog\/wp-json\/wp\/v2\/tags?post=3513"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}