{"id":3245,"date":"2017-01-23T19:55:52","date_gmt":"2017-01-23T19:55:52","guid":{"rendered":"https:\/\/marketingweb.com.mx\/blog\/?p=3245"},"modified":"2017-01-23T19:55:52","modified_gmt":"2017-01-23T19:55:52","slug":"desarrollo-web-3","status":"publish","type":"post","link":"https:\/\/marketingweb.com.mx\/blog\/desarrollo-web-3\/","title":{"rendered":"Desarrollo Web DF"},"content":{"rendered":"<h1>Desarrollo Web DF<\/h1>\n<figure id=\"attachment_3232\" aria-describedby=\"caption-attachment-3232\" style=\"width: 300px\" class=\"wp-caption alignnone\"><a href=\"https:\/\/marketingweb.com.mx\/blog\/wp-content\/uploads\/j.png\"><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-3232\" src=\"https:\/\/marketingweb.com.mx\/blog\/wp-content\/uploads\/j-300x192.png\" alt=\"Desarrollo Web DF\" width=\"300\" height=\"192\" srcset=\"https:\/\/marketingweb.com.mx\/blog\/wp-content\/uploads\/j-300x192.png 300w, https:\/\/marketingweb.com.mx\/blog\/wp-content\/uploads\/j.png 625w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><figcaption id=\"caption-attachment-3232\" class=\"wp-caption-text\"><em>Desarrollo Web DF<\/em><\/figcaption><\/figure>\n<p><em><strong>Desarrollo Web DF.\u00a0<\/strong><\/em>\u201cLos <strong>dise\u00f1os web<\/strong> m\u00e1s efectivos para un p\u00fablico general de Internet (en su mayor\u00eda con conexi\u00f3n v\u00eda m\u00f3dem) son una cuidada y equilibrada mezcla de textos y enlaces, con elementos gr\u00e1ficos relativamente peque\u00f1os. Este tipo de p\u00e1gina se descarga muy r\u00e1pido, incluso cuando se accede a ellas con velocidades de 28,8 kbps, y aun as\u00ed consiguen un fuerte impacto visual\u201d\u00a0 (Lynch y Horton, 2000; 55).<\/p>\n<p>Fern\u00e1ndez-Coca (1998) se\u00f1ala seis elementos b\u00e1sicos que componen la estructura de una p\u00e1gina Web.<\/p>\n<ul>\n<li><strong>Encabezamiento o banda de localizaci\u00f3n.<\/strong> Es la primera informaci\u00f3n que visualiza el usuario al descargar el <strong>desarrollo web DF\u00a0<\/strong>de la p\u00e1gina. Su funci\u00f3n identificar claramente el sitio al que pertenece mediante la inclusi\u00f3n de un logotipo, el nombre de la instituci\u00f3n o la utilizaci\u00f3n de alg\u00fan color identificatorio. Adem\u00e1s, debe permitir que el usuario pueda ubicar f\u00e1cilmente el lugar que ocupa la p\u00e1gina en la estructura global del sitio. Esta informaci\u00f3n pude presentarse en modo gr\u00e1fico o de texto. Fern\u00e1ndez-Coca (1998) advierte que si se opta por una presentaci\u00f3n de tipo gr\u00e1fico debe incluirse una etiqueta \u201cALT\u201d\u00a0para que la informaci\u00f3n sea tambi\u00e9n accesible a los usuarios que no puedan ver la imagen. Nielsen (2000) recomienda colocar una barra horizontal que vaya se\u00f1alando los diversos lugares por los que ha atravesado hasta llegar a la p\u00e1gina que est\u00e1 viendo, tomando como referencia la p\u00e1gina principal. Por ejemplo, si un usuario abre la <em>home page<\/em> de un sitio, luego ingresa en la secci\u00f3n \u201csalud\u201d y posteriormente sigue el enlace \u201cmedicamentos\u201d, el encabezado de la p\u00e1gina deber\u00eda mostrar cada uno de los lugares por los cuales atraves\u00f3 para llegar a la p\u00e1gina de \u201cmedicamentos\u201d.<\/li>\n<\/ul>\n<ul>\n<li><strong>Iconos o enlaces hipertexto de navegaci\u00f3n b\u00e1sica.<\/strong> Si el sitio contiene muchas p\u00e1ginas largas en las que el usuario debe hacer <em>scroll<\/em> para visualizar la totalidad de su contenido, conviene colocar en la parte superior una serie de enlaces con los principales punto de referencia del sitio como la p\u00e1gina principal, la ayuda y la p\u00e1gina anterior. Estos enlaces se pueden realizar a trav\u00e9s de hipertexto o mediante \u00edconos o botones gr\u00e1ficos, por lo que hay que agregarlos con anterioridad en el <strong>Dise\u00f1o web Guadalajara<\/strong>. En ambos casos conviene que esta estructura \u2013tambi\u00e9n denominada barra de navegaci\u00f3n- se mantenga constante y ofrezca a lo largo de cada una de las p\u00e1ginas del sitio las mismas opciones.<\/li>\n<li>Es la zona de la p\u00e1gina donde se incluye la informaci\u00f3n espec\u00edfica. Las normas de estilo gr\u00e1fico utilizadas para presentar la informaci\u00f3n deben mantenerse a lo largo del sitio.<\/li>\n<li><strong>Notas de pie de p\u00e1gina.<\/strong> Si se publica en la Web documentos con citas al pie, es conveniente que est\u00e9n en la misma p\u00e1gina donde se encuentran las referencias para evitar que el usuario cargue una nueva p\u00e1gina. Adem\u00e1s, deben separarse las citas del resto del texto mediante alg\u00fan recurso visual como una l\u00ednea, un espacio en blanco o cambio en la tipograf\u00eda y el tama\u00f1o de los caracteres.<\/li>\n<li><strong>Firma, fecha y correo electr\u00f3nico.<\/strong> Conocer qui\u00e9n es el responsable del documento, cuando fue confeccionada la p\u00e1gina y tener la posibilidad de establecer contacto con la persona u organizaci\u00f3n que publica el sitio es una forma de transmitir confianza al usuario.<\/li>\n<\/ul>\n<p>Desarrollo Web DF<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Desarrollo Web DF Desarrollo Web DF.\u00a0\u201cLos dise\u00f1os web m\u00e1s efectivos para un p\u00fablico general de Internet (en su mayor\u00eda con conexi\u00f3n v\u00eda m\u00f3dem) son una cuidada y equilibrada mezcla de textos y enlaces, con elementos gr\u00e1ficos relativamente peque\u00f1os. Este tipo de p\u00e1gina se descarga muy r\u00e1pido, incluso cuando se accede a ellas con velocidades de [&hellip;]<\/p>\n","protected":false},"author":18,"featured_media":3232,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_joinchat":[],"footnotes":""},"categories":[55],"tags":[500,483,282,330,480,364,48,493,490,479],"class_list":["post-3245","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-diseno-web","tag-agencia-de-desarrollo-web-a","tag-agencia-de-desarrollo-web-ciudad-de-mexico","tag-agencia-de-diseno-web","tag-agencia-de-diseno-web-guadalajara","tag-desarrollo-web-ciudad-de-mexico","tag-desarrollo-web-df","tag-diseno-de-pagina-web","tag-diseno-de-paginas-web-ciudad-de-mexico","tag-diseno-de-paginas-web-guadalajara","tag-guadalajara-diseno-web"],"_links":{"self":[{"href":"https:\/\/marketingweb.com.mx\/blog\/wp-json\/wp\/v2\/posts\/3245","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/marketingweb.com.mx\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/marketingweb.com.mx\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/marketingweb.com.mx\/blog\/wp-json\/wp\/v2\/users\/18"}],"replies":[{"embeddable":true,"href":"https:\/\/marketingweb.com.mx\/blog\/wp-json\/wp\/v2\/comments?post=3245"}],"version-history":[{"count":0,"href":"https:\/\/marketingweb.com.mx\/blog\/wp-json\/wp\/v2\/posts\/3245\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/marketingweb.com.mx\/blog\/wp-json\/wp\/v2\/media\/3232"}],"wp:attachment":[{"href":"https:\/\/marketingweb.com.mx\/blog\/wp-json\/wp\/v2\/media?parent=3245"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/marketingweb.com.mx\/blog\/wp-json\/wp\/v2\/categories?post=3245"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/marketingweb.com.mx\/blog\/wp-json\/wp\/v2\/tags?post=3245"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}