{"id":2870,"date":"2016-10-07T00:27:24","date_gmt":"2016-10-07T00:27:24","guid":{"rendered":"https:\/\/marketingweb.com.mx\/blog\/?p=2870"},"modified":"2016-10-11T16:58:49","modified_gmt":"2016-10-11T16:58:49","slug":"posicionamiento-web-df","status":"publish","type":"post","link":"https:\/\/marketingweb.com.mx\/blog\/posicionamiento-web-df\/","title":{"rendered":"Posicionamiento web DF"},"content":{"rendered":"<h1>Posicionamiento web DF<\/h1>\n<p><a href=\"https:\/\/marketingweb.com.mx\/blog\/wp-content\/uploads\/01-silver-feather-photo-video-studio-website-design1-1.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-2663\" src=\"https:\/\/marketingweb.com.mx\/blog\/wp-content\/uploads\/01-silver-feather-photo-video-studio-website-design1-1-300x200.jpg\" alt=\"Posicionamiento web df\" width=\"300\" height=\"200\" srcset=\"https:\/\/marketingweb.com.mx\/blog\/wp-content\/uploads\/01-silver-feather-photo-video-studio-website-design1-1-300x200.jpg 300w, https:\/\/marketingweb.com.mx\/blog\/wp-content\/uploads\/01-silver-feather-photo-video-studio-website-design1-1-768x512.jpg 768w, https:\/\/marketingweb.com.mx\/blog\/wp-content\/uploads\/01-silver-feather-photo-video-studio-website-design1-1-1024x683.jpg 1024w, https:\/\/marketingweb.com.mx\/blog\/wp-content\/uploads\/01-silver-feather-photo-video-studio-website-design1-1.jpg 1500w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<p>&nbsp;<\/p>\n<p>Los factores que los buscadores consideran para inferir\u00a0el <strong>posicionamiento web df<\/strong>\u00a0de una p\u00e1gina y que se basan en datos que recogen fuera de la propia p\u00e1gina y\/o sitio a que pertenece, ya sea que la p\u00e1gina sea del <b>DF<\/b>\u00a0o no. B\u00e1sicamente se analizan los <strong>enlaces<\/strong> externos que apuntan a las p\u00e1ginas del sitio Web y el texto de dicho enlace (texto ancla). En dicho an\u00e1lisis se tienen en cuenta factores como:<\/p>\n<ul>\n<li>El n\u00famero de <strong>enlaces externos<\/strong>, si bien hay que tener en cuenta que no todos los enlaces tienen el mismo peso. No es lo mismo tener un <strong>enlace externo<\/strong> desde un sitio de alta relevancia que desde uno completamente an\u00f3nimo.<\/li>\n<li>La relevancia de las p\u00e1ginas en la que se encuentran dichos<strong> enlaces<\/strong>. Y no solamente su relevancia en t\u00e9rminos absolutos, sino tambi\u00e9n considerando la tem\u00e1tica general de cada uno de los sitios. Por ejemplo, un enlace de un Web de alta relevancia sobre bricolaje a una ferreter\u00eda cuenta mucho m\u00e1s que un enlace de dicho Web a una tienda de animales dom\u00e9sticos.<\/li>\n<li>Las palabras que se han usado en el enlace. Se tienen muy en cuenta. De hecho en ocasiones los buscadores muestran como resultado para una b\u00fasqueda dada, p\u00e1ginas que no contienen el t\u00e9rmino buscado. En su lugar hay un <strong>enlace externo<\/strong> que apunta a dicho resultado con los t\u00e9rminos introducidos en la b\u00fasqueda. Pongamos un ejemplo: tenemos una p\u00e1gina sobre alquiler de apartamentos en Almu\u00f1ecar. Supongamos que dicha p\u00e1gina no contiene la palabra \u2018reserva\u2019. Y supongamos tambi\u00e9n que hay un enlace externo a dicha p\u00e1gina con el texto ancla \u2018reserva de apartamentos\u2019. Pues bien: por la importancia que conceden los buscadores a las palabras presentes en el texto ancla, podr\u00eda darse el caso en que nuestra p\u00e1gina de alquiler de apartamentos en Almu\u00f1ecar apareciese como resultado para la b\u00fasqueda \u2018reserva de apartamentos\u2019.<\/li>\n<\/ul>\n<p>La <strong>diversidad y dispersi\u00f3n<\/strong> de dichas palabras. Existen mecanismos no l\u00edcitos que permiten la creaci\u00f3n autom\u00e1tica de enlaces con el objeto de enga\u00f1ar a los buscadores y conseguir enlaces. Estos enlaces generados autom\u00e1ticamente suelen\u00a0tener un texto ancla m\u00e1s o menos fijo. Sin embargo, los enlaces \u201cnormales\u201d generados por humanos suelen tener textos ancla ligeramente diferentes. Los buscadores han desarrollado mecanismos para diferenciar enlaces autom\u00e1ticos de enlaces naturales mediante el an\u00e1lisis de la dispersi\u00f3n de los textos ancla.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Posicionamiento web DF &nbsp; Los factores que los buscadores consideran para inferir\u00a0el posicionamiento web df\u00a0de una p\u00e1gina y que se basan en datos que recogen fuera de la propia p\u00e1gina y\/o sitio a que pertenece, ya sea que la p\u00e1gina sea del DF\u00a0o no. B\u00e1sicamente se analizan los enlaces externos que apuntan a las p\u00e1ginas [&hellip;]<\/p>\n","protected":false},"author":18,"featured_media":2663,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_joinchat":[],"footnotes":""},"categories":[58,20],"tags":[94,95,269,96,268],"class_list":["post-2870","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-posicionamiento-web","category-seo","tag-posicionamiento","tag-posicionamiento-buscadores","tag-posicionamiento-ciudad-de-mexico","tag-posicionamiento-de-buscadores","tag-posicionamiento-df"],"_links":{"self":[{"href":"https:\/\/marketingweb.com.mx\/blog\/wp-json\/wp\/v2\/posts\/2870","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/marketingweb.com.mx\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/marketingweb.com.mx\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/marketingweb.com.mx\/blog\/wp-json\/wp\/v2\/users\/18"}],"replies":[{"embeddable":true,"href":"https:\/\/marketingweb.com.mx\/blog\/wp-json\/wp\/v2\/comments?post=2870"}],"version-history":[{"count":0,"href":"https:\/\/marketingweb.com.mx\/blog\/wp-json\/wp\/v2\/posts\/2870\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/marketingweb.com.mx\/blog\/wp-json\/wp\/v2\/media\/2663"}],"wp:attachment":[{"href":"https:\/\/marketingweb.com.mx\/blog\/wp-json\/wp\/v2\/media?parent=2870"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/marketingweb.com.mx\/blog\/wp-json\/wp\/v2\/categories?post=2870"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/marketingweb.com.mx\/blog\/wp-json\/wp\/v2\/tags?post=2870"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}