{"id":10523,"date":"2024-12-21T22:02:00","date_gmt":"2024-12-22T04:02:00","guid":{"rendered":"https:\/\/marketingweb.com.mx\/blog\/los-mejores-trucos-para-utilizar-whatsapp-como-un-experto-tu-tecnologia-el-pais\/"},"modified":"2024-12-21T22:02:00","modified_gmt":"2024-12-22T04:02:00","slug":"los-mejores-trucos-para-utilizar-whatsapp-como-un-experto-tu-tecnologia-el-pais","status":"publish","type":"post","link":"https:\/\/marketingweb.com.mx\/blog\/los-mejores-trucos-para-utilizar-whatsapp-como-un-experto-tu-tecnologia-el-pais\/","title":{"rendered":"Los mejores trucos para utilizar WhatsApp como un experto | Tu Tecnolog\u00eda | El Pa\u00eds"},"content":{"rendered":"<p> [ad_1]<br \/>\n<br \/><img decoding=\"async\" src=\"https:\/\/imagenes.elpais.com\/resizer\/v2\/4QHXPX3XHBENJKWSTRPQPF7C6I.jpg?auth=dac2079d86c661924d3e8f26d0b78f960ea00f1e456d0ae2afcec2f9192565d8\" \/><\/p>\n<div data-dtm-region=\"articulo_cuerpo\">\n<p class=\"\">Con una base estimada de casi tres mil millones de usuarios repartidos por todo el mundo,<a href=\"https:\/\/elpais.com\/tecnologia\/tu-tecnologia\/2024-10-12\/asi-funciona-rcs-la-nueva-mensajeria-de-texto-que-amenaza-con-desbancar-a-whatsapp.html\" target=\"_blank\" rel=\"noopener\"> WhatsApp se ha convertido en un est\u00e1ndar de comunicaci\u00f3n<\/a>. Hasta tiene su <i>rinconcito<\/i> en la Real Academia de la Lengua, como expresi\u00f3n de uso habitual. La universalidad de la aplicaci\u00f3n de Meta ha logrado que sea utilizada de forma masiva desde los m\u00e1s j\u00f3venes hasta ancianos; sin embargo, esconde una serie de funciones muy pr\u00e1cticas que no son tan conocidas por la mayor\u00eda de los usuarios.<\/p>\n<p class=\"\">Muchos usuarios se sorprenden al ver c\u00f3mo otros enriquecen sus mensajes con negritas y cursivas. Y solo entre los m\u00e1s expertos es habitual fisgonear parte de los mensajes sin que el remitente <a href=\"https:\/\/elpais.com\/tecnologia\/tu-tecnologia\/2024-06-24\/me-esta-ignorando-como-saber-si-han-leido-tu-mensaje-en-whatsapp.html\" target=\"_blank\" rel=\"noopener\">reciba el doble <i>check<\/i> azul<\/a>. Estas son los trucos que m\u00e1s pueden disparar el potencial de WhatsApp:<\/p>\n<h3 class=\"\">C\u00f3mo leer mensajes sin que se sepa<\/h3>\n<p class=\"\">No hay mayor presi\u00f3n que abrir un mensaje y saber que el remitente es consciente de su lectura. \u00bfPuede fisgonearse un mensaje de forma subrepticia? S\u00ed, en parte. Para leer un mensaje en WhatsApp sin activar el doble <i>check<\/i> azul, se puede usar la vista previa de notificaciones del dispositivo: cuando llega un mensaje, en lugar de abrir WhatsApp, hay que revisar el contenido desde la notificaci\u00f3n emergente o la barra de notificaciones del sistema. Si el mensaje es largo, deslizar hacia abajo en la notificaci\u00f3n (<a href=\"https:\/\/elpais.com\/noticias\/iphone\/\" target=\"_blank\" rel=\"noopener\">en iPhone<\/a>) o expandirla (<a href=\"https:\/\/elpais.com\/noticias\/android\/\" target=\"_blank\" rel=\"noopener\">en Android<\/a>) permite ver m\u00e1s contenido sin que el remitente reciba confirmaci\u00f3n de lectura.<\/p>\n<aside class=\"a_ei\">\n<header class=\"a_ei_h _db\">M\u00e1s informaci\u00f3n<\/header>\n<\/aside>\n<h3 class=\"\">Marcar mensajes como no le\u00eddos<\/h3>\n<p class=\"\">\u00bfQu\u00e9 sucede cuando leemos un mensaje con un contenido importante que no podemos atender en el momento? Meta ha contemplado esta circunstancia y para recordar mensajes sin responder de inmediato, la opci\u00f3n de marcar como no le\u00eddo permite tener el chat destacado en la lista de conversaciones, actuando como un recordatorio visual sin afectar el estado de lectura. Este ajuste es solo visual y no afecta a los <i>checks<\/i> azules. Para marcar un mensaje como no le\u00eddo en WhatsApp:<\/p>\n<ul>\n<li><span>En Android: hay que mantener presionado el chat deseado en la lista de conversaciones. Y a continuaci\u00f3n, en el men\u00fa superior, seleccionar la opci\u00f3n \u2018Marcar como no le\u00eddo\u2019. El chat aparecer\u00e1 con un punto verde, indicando que queda pendiente de revisar.<\/span><\/li>\n<li><span>En iPhone: hay que deslizar el chat hacia la derecha en la lista de conversaciones y tocar \u2018Marcar como no le\u00eddo\u2019.<\/span><\/li>\n<\/ul>\n<h3 class=\"\">Fijar chats en la parte superior<\/h3>\n<p class=\"\">Por lo general, siempre mantenemos conversaciones con determinadas personas con mayor frecuencia. Para acceder a ellas de forma m\u00e1s r\u00e1pida, WhatsApp permite fijarlos en la parte superior de la app. Los chats de contactos o grupos importantes se pueden fijar en la parte superior de la lista para tenerlos siempre a mano. Eso s\u00ed, la plataforma establece un m\u00e1ximo de tres conversaciones fijadas. Para fijarlas hay que:<\/p>\n<ul>\n<li><span>En Android: mantener presionado el chat y seleccionar el icono de la chincheta.<\/span><\/li>\n<li><span>En iPhone: deslizar el chat hacia la derecha y seleccionar \u2018Fijar\u2019.<\/span><\/li>\n<\/ul>\n<h3 class=\"\">Enviar mensajes temporales<\/h3>\n<p class=\"\">Los mensajes temporales a\u00f1aden privacidad a las conversaciones, ya que desaparecen de forma autom\u00e1tica tras un periodo definido \u2014 de 24 horas, 7 d\u00edas o 90 d\u00edas\u2014. Esto es especialmente \u00fatil para charlas sensibles o que contienen informaci\u00f3n temporal, pero tambi\u00e9n para minimizar el almacenamiento, puesto que los mensajes antiguos se eliminan autom\u00e1ticamente despu\u00e9s de un periodo espec\u00edfico. Estos son los pasos para hacer temporal el contenido de una conversaci\u00f3n:<\/p>\n<ol>\n<li><span>Abrir el chat deseado y tocar el nombre del contacto o grupo.<\/span><\/li>\n<li><span>Seleccionar \u2018Mensajes temporales\u2019.<\/span><\/li>\n<li><span>Elegir el tiempo de duraci\u00f3n: 24 horas, 7 d\u00edas o 90 d\u00edas.<\/span><\/li>\n<\/ol>\n<h3 class=\"\">\u201cEsta foto solo se podr\u00e1 ver una vez\u201d<\/h3>\n<p class=\"\">Enviar fotos o videos temporales en WhatsApp es \u00fatil para compartir contenido sensible o ef\u00edmero que no se desea guardar en el chat. Esta funci\u00f3n es ideal para enviar informaci\u00f3n visual r\u00e1pida (como fotos de documentos, contrase\u00f1as temporales, o im\u00e1genes privadas) que el destinatario solo necesita ver una vez y que no quedar\u00e1n almacenadas en su galer\u00eda ni en el historial de conversaci\u00f3n. Adem\u00e1s, reduce el riesgo de que el contenido se comparta accidentalmente o permanezca visible en el futuro.<\/p>\n<h3 class=\"\">Usar WhatsApp en modo oculto<\/h3>\n<p class=\"\">Activar el modo avi\u00f3n antes de abrir WhatsApp permite leer mensajes sin aparecer en l\u00ednea ni enviar confirmaci\u00f3n de lectura. cerrar la app y desactivar el modo avi\u00f3n. La funci\u00f3n de leer mensajes en modo oculto es \u00fatil cuando se desea ver los mensajes de un chat sin notificar al remitente, ni aparecer en l\u00ednea. Este m\u00e9todo resulta especialmente conveniente para quienes quieren revisar una conversaci\u00f3n sin interrupciones o sin sentirse comprometidos a responder de inmediato. Estos son los pasos para utilizarlo de manera ocasional:<\/p>\n<ol>\n<li><span>Antes de abrir WhatsApp, hay que activar el modo avi\u00f3n en el dispositivo, asegur\u00e1ndose adem\u00e1s de desconectar las conexiones a redes wifi.<\/span><\/li>\n<li><span>Abrir WhatsApp y lea los mensajes.<\/span><\/li>\n<li><span>Tras revisar los mensajes, es importante cerrar completamente la aplicaci\u00f3n antes de desactivar el modo avi\u00f3n.<\/span><\/li>\n<\/ol>\n<p class=\"\">Este proceso evita que el sistema registre la lectura o la conexi\u00f3n. Eso s\u00ed, tan pronto como recupere la conexi\u00f3n, el remitente sabr\u00e1 que lo ha le\u00eddo. Si se quiere usar el modo oculto con frecuencia, es m\u00e1s pr\u00e1ctico ir a las opciones de \u2018Ajustes &gt; Privacidad\u2019 en el men\u00fa de WhatsApp: ah\u00ed, el usuario puede elegir que nadie pueda ver cu\u00e1ndo fue la \u00faltima hora a la que se conect\u00f3, o si est\u00e1 en l\u00ednea en ese momento; adem\u00e1s, puede eliminar los dobles <i>checks<\/i> azules \u2014solo en conversaciones individuales, en grupos van a aparecer siempre\u2014 si desactiva la opci\u00f3n \u2018Confirmaciones de lectura\u2019. Es importante destacar que al hacer eso, el usuario tampoco podr\u00e1 ver los <i>checks<\/i> ni las horas de conexi\u00f3n de los dem\u00e1s usuarios, ni tampoco saber si est\u00e1n en l\u00ednea en ese momento.<\/p>\n<h3 class=\"\">Enviar la ubicaci\u00f3n en tiempo real<\/h3>\n<p class=\"\">Compartir la ubicaci\u00f3n en tiempo real en WhatsApp es una herramienta pr\u00e1ctica en situaciones en las que alguien necesita conocer su posici\u00f3n exacta; por ejemplo, en el transcurso de un viaje o para coordinar un encuentro. Esta funci\u00f3n permite que el destinatario siga su ubicaci\u00f3n en un mapa, en tiempo real, durante el periodo que elija: 15 minutos, 1 hora o 8 horas.<\/p>\n<ul>\n<li><span>Para activarlo hay que abrir el chat, tocar el icono de adjuntar (clip en Android o \u2018+\u2019 en iPhone) y seleccionar \u2018Ubicaci\u00f3n &gt; Ubicaci\u00f3n en tiempo real\u2019. Tambi\u00e9n se puede cancelar en cualquier momento antes de que el tiempo termine.<\/span><\/li>\n<\/ul>\n<h3 class=\"\">Formatear el texto en los mensajes<\/h3>\n<p class=\"\">Los mensajes de WhatsApp no tienen por qu\u00e9 ser planos y aburridos: para dar formato a los mensajes de texto en WhatsApp y hacer que la conversaci\u00f3n sea m\u00e1s din\u00e1mica y clara, se pueden aplicar distintas opciones de estilo:<\/p>\n<ul>\n<li><span><b>Negrita<\/b>: para destacar palabras clave, hay que a\u00f1adir un asterisco (*) al inicio y final de la palabra o frase. Por ejemplo, as\u00ed: *texto*.<\/span><\/li>\n<li><span><i>Cursiva<\/i>: se consigue con guiones bajos (_), de la siguiente manera: _texto_.<\/span><\/li>\n<li><span>Tachado: con una virgulilla (~) al principio y al final, as\u00ed: ~texto~.<\/span><\/li>\n<li><span>Monoespaciado: con tres acentos graves (&#8220;`) al inicio y final para dar un estilo de tipo fijo: &#8220;`texto&#8220;`.<\/span><\/li>\n<\/ul>\n<p class=\"\">Adem\u00e1s, tanto en Android como en iPhone, si no se recuerdan esos caracteres especiales modificadores, pueden aplicarse estas opciones seleccionando el texto y escogiendo en el men\u00fa contextual el formato deseado.<\/p>\n<h3 class=\"\">Enviarse mensajes a uno mismo<\/h3>\n<p class=\"\">WhatsApp puede ser una herramienta de organizaci\u00f3n para uno mismo, con algo tan b\u00e1sico como crear un espacio personal donde los usuarios pueden autoenviarse mensajes, enlaces, archivos o cualquier tipo de recordatorio. Este recurso es ideal para aquellos que buscan mantener informaci\u00f3n importante o temporal a mano, sin depender de una aplicaci\u00f3n externa de notas. Estos son los pasos para hacerlo:<\/p>\n<ol>\n<li><span>Abrir la aplicaci\u00f3n y, en la lista de contactos, buscar el n\u00famero de tel\u00e9fono propio.<\/span><\/li>\n<li><span>Iniciar un chat con su propio contacto personal y enviar cualquier mensaje, enlace, archivo o nota que desee guardar.<\/span><\/li>\n<li><span>Todo lo que se env\u00ede a este chat queda cifrado y almacenado en un hilo personal.<\/span><\/li>\n<\/ol>\n<h3 class=\"\">Crear accesos directos a chats<\/h3>\n<p class=\"\">Adem\u00e1s de anclar en la parte superior de la app las conversaciones m\u00e1s recurrentes, en Android se puede hacer que aparezcan como un icono aparte en la pantalla de inicio del m\u00f3vil. Con esta opci\u00f3n, se pueden crear accesos directos a los chats de WhatsApp m\u00e1s importantes, agilizando as\u00ed la entrada a conversaciones frecuentes sin tener que abrir as\u00ed la aplicaci\u00f3n completa. Para conseguirlo, hay que dar estos pasos:<\/p>\n<ol>\n<li><span>En la lista de chats, mantener presionado el chat deseado.<\/span><\/li>\n<li><span>Tocar el men\u00fa de tres puntos en la esquina superior derecha.<\/span><\/li>\n<li><span>Seleccionar \u2018Crear acceso directo\u2019. As\u00ed aparecer\u00e1 un icono en la pantalla de inicio que enlaza directamente al chat.<\/span><\/li>\n<\/ol>\n<\/div>\n<p>[ad_2]<br \/>\n<br \/><a href=\"https:\/\/elpais.com\/tecnologia\/tu-tecnologia\/2024-11-06\/los-mejores-trucos-para-utilizar-whatsapp-como-un-experto.html\" target=\"_blank\" rel=\"noopener\">Source link <\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>[ad_1] Con una base estimada de casi tres mil millones de usuarios repartidos por todo el mundo, WhatsApp se ha convertido en un est\u00e1ndar de comunicaci\u00f3n. Hasta tiene su rinconcito en la Real Academia de la Lengua, como expresi\u00f3n de uso habitual. La universalidad de la aplicaci\u00f3n de Meta ha logrado que sea utilizada de [&hellip;]<\/p>\n","protected":false},"author":18,"featured_media":10524,"comment_status":"open","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"_joinchat":[],"footnotes":""},"categories":[20],"tags":[],"class_list":["post-10523","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-seo"],"_links":{"self":[{"href":"https:\/\/marketingweb.com.mx\/blog\/wp-json\/wp\/v2\/posts\/10523","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/marketingweb.com.mx\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/marketingweb.com.mx\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/marketingweb.com.mx\/blog\/wp-json\/wp\/v2\/users\/18"}],"replies":[{"embeddable":true,"href":"https:\/\/marketingweb.com.mx\/blog\/wp-json\/wp\/v2\/comments?post=10523"}],"version-history":[{"count":0,"href":"https:\/\/marketingweb.com.mx\/blog\/wp-json\/wp\/v2\/posts\/10523\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/marketingweb.com.mx\/blog\/wp-json\/wp\/v2\/media\/10524"}],"wp:attachment":[{"href":"https:\/\/marketingweb.com.mx\/blog\/wp-json\/wp\/v2\/media?parent=10523"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/marketingweb.com.mx\/blog\/wp-json\/wp\/v2\/categories?post=10523"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/marketingweb.com.mx\/blog\/wp-json\/wp\/v2\/tags?post=10523"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}